{"id":27973,"date":"2024-09-06T22:17:05","date_gmt":"2024-09-06T22:17:05","guid":{"rendered":"https:\/\/abuelaenlacocina.com\/?p=27973"},"modified":"2024-09-06T22:17:07","modified_gmt":"2024-09-06T22:17:07","slug":"como-propagar-cultivar-suculenta-delfin-y-sus-cuidados","status":"publish","type":"post","link":"https:\/\/abuelaenlacocina.com\/index.php\/2024\/09\/06\/como-propagar-cultivar-suculenta-delfin-y-sus-cuidados\/","title":{"rendered":"C\u00f3mo propagar, cultivar Suculenta Delf\u00edn y sus cuidados"},"content":{"rendered":"\n<p>Esta adorable suculenta te dar\u00e1 vibraciones playeras durante todo el d\u00eda porque, haciendo honor a su nombre, sus hojas se asemejan a una manada de delfines saltando. La suculenta delf\u00edn (Senecio peregrinus) es un h\u00edbrido del cord\u00f3n de perlas (Senecio rowleyanus) y de la planta vela (Senecio articulatus). En este art\u00edculo veremos c\u00f3mo propagar, cultivar suculenta delf\u00edn y sus cuidados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Datos b\u00e1sicos<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Nombre bot\u00e1nico<\/strong>:\u00a0Senecio peregrinus<\/li>\n\n\n\n<li><strong>Nombre com\u00fan:<\/strong>\u00a0Cadena de delfines, planta de delfines, delfines voladores, collar de delfines<\/li>\n\n\n\n<li><strong>Tipo de planta:<\/strong>\u00a0Suculenta<\/li>\n\n\n\n<li><strong>Tama\u00f1o de madurez:<\/strong>\u00a015 cm de altura<\/li>\n\n\n\n<li><strong>Exposici\u00f3n al sol:<\/strong>\u00a0Sol total o parcial<\/li>\n\n\n\n<li><strong>Tipo de suelo:<\/strong>\u00a0bien drenado, para cactus\/suculentas<\/li>\n\n\n\n<li><strong>\u00c9poca de floraci\u00f3n:<\/strong>\u00a0Primavera<\/li>\n\n\n\n<li><strong>Color de la flor:<\/strong>\u00a0Blanco<\/li>\n\n\n\n<li><strong>Toxicidad:<\/strong>\u00a0T\u00f3xica para perros y gatos<\/li>\n<\/ul>\n\n\n\n<p>Como la suculenta delf\u00edn es una variedad cruzada, no es una planta muy com\u00fan y puede ser dif\u00edcil de encontrar. Sin embargo, una r\u00e1pida b\u00fasqueda en Internet muestra que hay cultivadores especializados y que puedes tener suerte encontr\u00e1ndola.<\/p>\n\n\n\n<p>No obstante, si conoces a alguien que tenga una planta puedes pedirle una rama (esqueje), ya que cultivar suculenta delf\u00edn por medio de esquejes es muy f\u00e1cil, en este art\u00edculo te ense\u00f1amos c\u00f3mo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Donde cultivar Suculenta Delf\u00edn<\/strong><\/h2>\n\n\n\n<p>Puedes cultivar suculenta delf\u00edn normalmente en interiores como planta de interior, aunque tambi\u00e9n pueden cultivarse en exteriores.<\/p>\n\n\n\n<p>Sin embargo, no es una suculenta tolerante a las heladas y requiere un clima c\u00e1lido durante todo el a\u00f1o para sobrevivir en el exterior.<\/p>\n\n\n\n<p>No es una planta amante de la sombra, y es imprescindible proporcionarle suficiente luz solar para que crezca de forma saludable.<\/p>\n\n\n\n<p>Coloca tu suculenta delf\u00edn en una ventana luminosa y soleada si la vas a cultivar dentro de tu casa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>C\u00f3mo propagar suculenta delf\u00edn<\/strong><\/h2>\n\n\n\n<p>La suculenta delf\u00edn puede propagarse f\u00e1cilmente a partir de esquejes en agua o en tierra.<\/p>\n\n\n\n<p>Toma esquejes que tengan al menos 2 o 3 nodos a lo largo del tallo para tener m\u00e1s posibilidades de \u00e9xito.<\/p>\n\n\n\n<p>Los nodos se encuentran en los puntos en los que las hojas emergen de los tallos y es donde crecer\u00e1n las nuevas ra\u00edces.<\/p>\n\n\n\n<p>Si propagas los esquejes de tallo en agua, retira las hojas del nodo inferior o de los dos inferiores para asegurarte de que las hojas no se pudran.<\/p>\n\n\n\n<p>Las ra\u00edces deber\u00edan desarrollarse en un par de semanas, momento en el que podr\u00e1s transferir el esqueje a la tierra.<\/p>\n\n\n\n<p>Si quieres plantarla en tierra, basta con enterrar unos cent\u00edmetros del esqueje en el sustrato y asegurarse de que \u00e9ste se mantiene h\u00famedo hasta que se desarrollen las ra\u00edces.<\/p>\n\n\n\n<p>Sabr\u00e1s si ha desarrollado ra\u00edces cuando veas nuevas hojas crecer, en ese momento puedes realizar el trasplante a una maceta mas grande.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"555\" height=\"500\" src=\"https:\/\/abuelaenlacocina.com\/wp-content\/uploads\/2024\/09\/image-163.png\" alt=\"\" class=\"wp-image-27975\" srcset=\"https:\/\/abuelaenlacocina.com\/wp-content\/uploads\/2024\/09\/image-163.png 555w, https:\/\/abuelaenlacocina.com\/wp-content\/uploads\/2024\/09\/image-163-300x270.png 300w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Cuidados de la Suculenta delf\u00edn<\/strong><\/h2>\n\n\n\n<p>La suculenta delf\u00edn se considera generalmente una planta de bajo mantenimiento. Sus hojas gruesas retienen el agua, lo que la hace tolerante a la sequ\u00eda, y no requiere ning\u00fan cuidado o mantenimiento especial para mantenerla feliz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Luz<\/h3>\n\n\n\n<p>Aunque puede quemarse f\u00e1cilmente con el sol directo cuando se cultiva en el exterior, cuando se cultiva como planta de interior, la suculenta delf\u00edn crece mejor cuando recibe al menos seis horas de luz solar al d\u00eda.<\/p>\n\n\n\n<p>Lo ideal es una ventana iluminada, pero tambi\u00e9n puede adaptarse a la luz media cuando se cultiva en interiores. Si es necesario, utiliza luces de cultivo para proporcionar luz adicional.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Suelo<\/h3>\n\n\n\n<p>Al igual que la mayor\u00eda de las suculentas, la suculenta delf\u00edn requiere un suelo \u00e1rido y con buen drenaje.<\/p>\n\n\n\n<p>Las mezclas de cactus\/suculentas disponibles en el mercado son adecuadas para esta planta, pero tambi\u00e9n puedes hacer tu propia mezcla en casa.<\/p>\n\n\n\n<p>Simplemente combina 2 partes de tierra para macetas, 1 parte de piedra p\u00f3mez o perlita y 1 parte de arena.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Agua<\/h3>\n\n\n\n<p>Las hojas de la cuerda de delfines pueden retener el agua durante un largo periodo de tiempo, por lo que se considera que toleran la sequ\u00eda y no requieren un riego regular.<\/p>\n\n\n\n<p>Deja que la tierra se seque completamente entre riegos para evitar la putrefacci\u00f3n de las ra\u00edces, y luego riega bien.<\/p>\n\n\n\n<p>Reduce el riego durante los meses de oto\u00f1o e invierno, cuando la planta entra en letargo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Temperatura y humedad<\/h3>\n\n\n\n<p>La suculenta delf\u00edn crece bien con temperaturas y niveles de humedad medios en el hogar cuando se cultiva en interiores.<\/p>\n\n\n\n<p>Curiosamente, aunque estas plantas no toleran las heladas, tienden a preferir temperaturas m\u00e1s frescas que las suculentas promedio. Toleran temperaturas invernales de hasta 4 grados Celsius.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Abono<\/h3>\n\n\n\n<p>No necesita un abono regular. De hecho, abonar en exceso esta planta puede hacer que las hojas pierdan su ic\u00f3nica forma de delf\u00edn.<\/p>\n\n\n\n<p>Sin embargo, pueden beneficiarse de una alimentaci\u00f3n ligera a principios de la primavera para ayudar a impulsar el crecimiento y fomentar la floraci\u00f3n.<\/p>\n\n\n\n<p>Suele recomendarse el uso de un fertilizante org\u00e1nico, como abono de lombriz, algas l\u00edquidas o emulsi\u00f3n de pescado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Maceta y trasplante<\/h3>\n\n\n\n<p>Esta suculenta trepadora tolera el enraizamiento y no necesita ser replantada regularmente. Sin embargo, cada pocos a\u00f1os hay que trasplantarla para refrescar su medio de cultivo y aumentar el tama\u00f1o de la maceta.<\/p>\n\n\n\n<p>Es importante utilizar una maceta con agujeros de drenaje adecuados para evitar la putrefacci\u00f3n de las ra\u00edces y el encharcamiento del suelo.<\/p>\n\n\n\n<p>La suculenta delf\u00edn puede ir bien tanto en macetas de pl\u00e1stico como de terracota, pero algunos jardineros prefieren la terracota porque ayuda a absorber el exceso de humedad del suelo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Plagas y enfermedades<\/h3>\n\n\n\n<p>Las plagas comunes de las plantas de interior, como los pulgones, las\u00a0cochinillas\u00a0y las\u00a0ara\u00f1as rojas, pueden ser un problema para la suculenta delf\u00edn.<\/p>\n\n\n\n<p>Estas plagas son chupadores de savia y, si no se tratan, pueden causar estragos en una planta sana.<\/p>\n\n\n\n<p>La suculenta delf\u00edn no es propensa a ninguna enfermedad en particular, salvo la podredumbre de las ra\u00edces, que est\u00e1 causada por el exceso de riego.<\/p>\n\n\n\n<p>Si se riega s\u00f3lo cuando la tierra est\u00e1 completamente seca, se planta en una maceta con agujeros de drenaje adecuados y se utiliza una mezcla de tierra que drene bien, no deber\u00eda haber ning\u00fan problema.<\/p>\n\n\n\n<p><a target=\"_blank\" href=\"https:\/\/twitter.com\/intent\/tweet?text=C%C3%B3mo%20propagar%2C%20cultivar%20Suculenta%20Delf%C3%ADn%20y%20sus%20cuidados&amp;url=https%3A%2F%2Fwww.ecojardinmagico.com%2Fcomo-propagar-cultivar-suculenta-delfin-y-sus-cuidados%2F\" rel=\"noreferrer noopener\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta adorable suculenta te dar\u00e1 vibraciones playeras durante todo el d\u00eda porque, haciendo honor a su nombre, sus hojas se asemejan a una manada de delfines saltando. La suculenta delf\u00edn &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"C\u00f3mo propagar, cultivar Suculenta Delf\u00edn y sus cuidados\" class=\"read-more button\" href=\"https:\/\/abuelaenlacocina.com\/index.php\/2024\/09\/06\/como-propagar-cultivar-suculenta-delfin-y-sus-cuidados\/#more-27973\" aria-label=\"More on C\u00f3mo propagar, cultivar Suculenta Delf\u00edn y sus cuidados\">Seguir leyendo<\/a><\/p>\n","protected":false},"author":5,"featured_media":27974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-27973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jardin-y-consejos","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","no-featured-image-padding"],"_links":{"self":[{"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/posts\/27973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/comments?post=27973"}],"version-history":[{"count":1,"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/posts\/27973\/revisions"}],"predecessor-version":[{"id":27976,"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/posts\/27973\/revisions\/27976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/media\/27974"}],"wp:attachment":[{"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/media?parent=27973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/categories?post=27973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abuelaenlacocina.com\/index.php\/wp-json\/wp\/v2\/tags?post=27973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}